{"id":217,"count":5,"description":"","link":"http:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/","name":"Carpenter Ant Damage","slug":"carpenter-ant-damage","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carpenter Ant Damage Archives - Allison Pest Control<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carpenter Ant Damage Archives - Allison Pest Control\" \/>\n<meta property=\"og:url\" content=\"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/\" \/>\n<meta property=\"og:site_name\" content=\"Allison Pest Control\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@allisonpest\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carpenter Ant Damage Archives - Allison Pest Control","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/","og_locale":"en_US","og_type":"article","og_title":"Carpenter Ant Damage Archives - Allison Pest Control","og_url":"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/","og_site_name":"Allison Pest Control","twitter_card":"summary_large_image","twitter_site":"@allisonpest","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/","url":"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/","name":"Carpenter Ant Damage Archives - Allison Pest Control","isPartOf":{"@id":"http:\/\/new.allisonpest.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/new.allisonpest.com\/blog\/tag\/carpenter-ant-damage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/new.allisonpest.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Carpenter Ant Damage"}]},{"@type":"WebSite","@id":"http:\/\/new.allisonpest.com\/blog\/#website","url":"http:\/\/new.allisonpest.com\/blog\/","name":"Allison Pest Control","description":"Never Worry About Bugs Again","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/new.allisonpest.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/new.allisonpest.com\/blog\/wp-json\/wp\/v2\/tags\/217"}],"collection":[{"href":"http:\/\/new.allisonpest.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/new.allisonpest.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/new.allisonpest.com\/blog\/wp-json\/wp\/v2\/posts?tags=217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}